{"id":1076,"date":"2013-11-21T13:27:37","date_gmt":"2013-11-21T11:27:37","guid":{"rendered":"http:\/\/emtools.ro\/blog\/?p=1076"},"modified":"2022-02-01T10:51:06","modified_gmt":"2022-02-01T08:51:06","slug":"despre-lanturile-de-ferastrau-stihl","status":"publish","type":"post","link":"http:\/\/emtools.ro\/blog\/despre-lanturile-de-ferastrau-stihl\/","title":{"rendered":"Despre lanturile de ferastrau STIHL"},"content":{"rendered":"<p style=\"text-align: justify;\">Un motoferastrau trebuie sa treaca prin lemn. Pentru aceasta nu are nevoie doar de un motor puternic, ci si de o garnitura de taiere perfect compatibila. Sina de ghidaj, lantul de ferastrau si roata de lant trebuie sa se potriveasca perfect pentru ca puterea motorului sa poata fi transpusa optim in eficienta de taiere autentica.<\/p>\n<p style=\"text-align: justify;\"><strong>Caracteristici ale lanturilor de ferastrau STIHL<\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li>Sistem de lubrifiere STIHL Oilomatic<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Canalele fine din elementele lantului duc uleiul la articulatiile acestuia. Elementele de actionare au pe ambele parti canale, in care se aduna ulei. In acest fel uleiul se distribuie mai bine pe suprafetele de alunecare ale sinelor de ghidaj, asigurand o lubrifiere cu 10% mai buna. Durata de viata a lanturilor este astfel marita.<!--more--><\/p>\n<ul style=\"text-align: justify;\">\n<li>Marcaje de service si uzura<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Majoritatea lanturilor STIHL de motoferastrau au marcaje pe dintii taietori, cu ajutorul carora se poate observa clar uzura. Acestea au si rolul de reper pentru slefuire si va ajuta sa pastrati unghiul de ascutire.<\/p>\n<ul style=\"text-align: justify;\">\n<li>\u00a0Lant calit prin inductie<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Prin calirea inductiva, canalul sinei devine mai rezistent la uzura. Sina de ghidaj tine considerabil mai mult.<\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\">Camp de service<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Campul de service contine informatii importante despre garnitura de taiere. Acestea sunt inscrise cu laser in corpul sinei si raman lizibile indiferent de intensitatea solicitarii.<\/p>\n<p style=\"text-align: justify;\"><strong>Tipuri de lanturi de ferastrau STIHL<\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li>Lant de ferastrau Picco Micro Mini 3 (PMM3)<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Este primul lant STIHL cu vibratii reduse pentru ferastraie usoare. Lantul este robust, rezistent, cu recul mic, cu putere foarte mare de taiere datorita rostului de taiere foarte ingust.<\/p>\n<ul style=\"text-align: justify;\">\n<li>Lant de ferastrau Picco Micro 3 (PM3)<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Exclusiv de la STIHL: lantul de ferastrau cu 3\/8&#8243; Picco Micro 3. Acest lant de ferastrau cu recul si vibratii scazute a fost dezvoltat special pentru motoferastraiele usoare si compacte. Acesta combina eficienta de taiere puternica cu calitatea ridicata a taieturii si confortul de lucru ridicat. Varianta de 1\/4&#8243; se evidentiaza printr-o constructie foarte plata si ingusta, in combinatie cu o diviziune mica a lantului. Acesta este ideal pentru emondoarele de inaltime.<\/p>\n<ul style=\"text-align: justify;\">\n<li>Lant de ferastrau Picco Super (PS)<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Pe langa lantul de 3\/8&#8243; PS3 este singurul lant de ferastrau Picco plin, cu dinti tip dalta. Prezinta mult mai multa eficienta decat cu toate celelalte lanturi de ferastrau cu profil ingust, cu elemente de 1,3 mm. Si are si mai multa putere de strapungere decat lantul de ferastrau PS3 de 3\/8&#8243;. Are o functionare linistita in timpul taierii, cu 15% mai putine vibratii. Impresioneaza prin excelentul comportament de utilizare si suprafata taiata foarte curat. Datorita eficientei de taiere ridicate, lantul este ideal pentru utilizarea in domeniul forestier.<\/p>\n<ul style=\"text-align: justify;\">\n<li>Lant de ferastrau Picco Super 3 (PS3)<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">PS3 este primul lant Picco de 3\/8&#8243; din lume cu dinti tip dalta. Are mai multa putere de taiere, rulare lina in taietura, asezare excelenta, taietura foarte curata, vibratii mici. Datorita fortei mici de inaintare este ideal pentru ingrijirea copacilor.<\/p>\n<ul style=\"text-align: justify;\">\n<li>Lant de ferastrau Picco Duro 3 (PD3)<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Este primul lant din lume cu profil jos, din metal dur. Ramane ascutit chiar si de pana la 4 ori mai mult timp decat lanturile tipice si este clar mai durabil. Mai ales la solicitari extreme. Lucreaza cu vibratii si recul reduse.<\/p>\n<ul style=\"text-align: justify;\">\n<li>Lant Carving Rapid Micro Special (RMS)<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Lant de ferastrau Confort, cu vibratii reduse, cu foarte buna eficienta de taiere. Datorita scurtarii muchiei dintilor nu mai este nevoie de apasare in timpul operatiei de strapungere. Atinge o viteza de strapungere considerabil mai mare decat a lanturilor de ferastrau traditionale de 1\/4&#8243;. Lant de ferastrau special pentru sculptori si peisagisti.<\/p>\n<ul style=\"text-align: justify;\">\n<li>Lant de ferastrau Rapid Micr (RM)<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Este lantul universal ideal pentru agricultura, silvicultura si constructii, cu ghidare excelenta si putere mare de taiere.<\/p>\n<ul style=\"text-align: justify;\">\n<li>Lant de ferastrau Rapid Micro 3 (RM3)<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Lant confortabil cu recul si vibratii reduse, si ghidare buna in taietura.<\/p>\n<ul style=\"text-align: justify;\">\n<li>Lant de ferastrau Rapid Super (RS)<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Este un lant foarte puternic, cu vibratii reduse, ghidare buna in taietura, precum si cu putere foarte mare de taiere si de patrundere.<\/p>\n<ul style=\"text-align: justify;\">\n<li>Lant de ferastrau Rapid Super 3 (RS3)<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Lant foarte puternic cu element de actionare cu cama. Cu recul mic, are o putere extrem de mare de taiere si de patrundere.<\/p>\n<ul style=\"text-align: justify;\">\n<li>Lant de ferastrau Rapid Duro (RD)<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Lant din metal dur, care ramane ascutit dupa utilizari frecvente si solicitari extreme (de exemplu la lemne murdare sau inghetate).<\/p>\n<ul style=\"text-align: justify;\">\n<li>Lant de ferastrau Rapid Duro 3 (RD3)<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Este primul lant de ferastrau STIHL de 0.325&#8243; cu dinti taietori din metal dur. Fara recul, are vibratii scazute. Rezista fara ascutire de pana la patru ori mai mult timp decat un lant standard. In acest fel Rapid Duro 3 ofera o eficienta de taiere ridicata chiar si la solicitari extreme. Este lantul de ferastrau ideal pentru ingrijirea copacilor si peisagistica.<\/p>\n<ul style=\"text-align: justify;\">\n<li>Lant de ferastrau Rapid Duro R (RDR)<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Lant special pentru cele mai dure utilizare (lemne cu cuie, materiale compozite sau sticla securizata). Dintii taietori sunt acoperiti complet cu placi rezistente din metal dur.<\/p>\n<hr \/>\n<p style=\"text-align: justify;\">Magazinul online\u00a0<strong>EMTools<\/strong>\u00a0ofera o gama diversa de produse <a href=\"https:\/\/www.vintex.ro\/75-motoferastraie-si-emondoare-de-inaltime\" target=\"_blank\" rel=\"noopener\"><strong>STIHL<\/strong><\/a>.\u00a0Click\u00a0pentru mai multe detalii despre produse, preturi, accesorii.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un motoferastrau trebuie sa treaca prin lemn. Pentru aceasta nu are nevoie doar de un motor puternic, ci si de o garnitura de taiere perfect compatibila. Sina de ghidaj, lantul de ferastrau si roata de lant trebuie sa se potriveasca perfect pentru ca puterea motorului sa poata fi transpusa optim in eficienta de taiere autentica. [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":1080,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[354,89,355,62],"class_list":["post-1076","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diverse","tag-ferastrau","tag-lanturi-de-ferastrau","tag-lanturi-stihl","tag-stihl"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Despre lanturile de ferastrau STIHL - blog emtools.ro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/emtools.ro\/blog\/despre-lanturile-de-ferastrau-stihl\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Despre lanturile de ferastrau STIHL - blog emtools.ro\" \/>\n<meta property=\"og:description\" content=\"Un motoferastrau trebuie sa treaca prin lemn. Pentru aceasta nu are nevoie doar de un motor puternic, ci si de o garnitura de taiere perfect compatibila. Sina de ghidaj, lantul de ferastrau si roata de lant trebuie sa se potriveasca perfect pentru ca puterea motorului sa poata fi transpusa optim in eficienta de taiere autentica. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/emtools.ro\/blog\/despre-lanturile-de-ferastrau-stihl\/\" \/>\n<meta property=\"og:site_name\" content=\"blog emtools.ro\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EMTools\" \/>\n<meta property=\"article:published_time\" content=\"2013-11-21T11:27:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-01T08:51:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/emtools.ro\/blog\/wp-content\/uploads\/2013\/11\/lanturi-stihl.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"440\" \/>\n\t<meta property=\"og:image:height\" content=\"205\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mihaela\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mihaela\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/emtools.ro\/blog\/despre-lanturile-de-ferastrau-stihl\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/emtools.ro\/blog\/despre-lanturile-de-ferastrau-stihl\/\"},\"author\":{\"name\":\"Mihaela\",\"@id\":\"https:\/\/emtools.ro\/blog\/#\/schema\/person\/f54fdd06ca546dcf0b14772c20884545\"},\"headline\":\"Despre lanturile de ferastrau STIHL\",\"datePublished\":\"2013-11-21T11:27:37+00:00\",\"dateModified\":\"2022-02-01T08:51:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/emtools.ro\/blog\/despre-lanturile-de-ferastrau-stihl\/\"},\"wordCount\":810,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/emtools.ro\/blog\/despre-lanturile-de-ferastrau-stihl\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/emtools.ro\/blog\/wp-content\/uploads\/2013\/11\/lanturi-stihl.jpg\",\"keywords\":[\"ferastrau\",\"lanturi de ferastrau\",\"lanturi stihl\",\"stihl\"],\"articleSection\":[\"Diverse\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/emtools.ro\/blog\/despre-lanturile-de-ferastrau-stihl\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/emtools.ro\/blog\/despre-lanturile-de-ferastrau-stihl\/\",\"url\":\"https:\/\/emtools.ro\/blog\/despre-lanturile-de-ferastrau-stihl\/\",\"name\":\"Despre lanturile de ferastrau STIHL - blog emtools.ro\",\"isPartOf\":{\"@id\":\"https:\/\/emtools.ro\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/emtools.ro\/blog\/despre-lanturile-de-ferastrau-stihl\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/emtools.ro\/blog\/despre-lanturile-de-ferastrau-stihl\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/emtools.ro\/blog\/wp-content\/uploads\/2013\/11\/lanturi-stihl.jpg\",\"datePublished\":\"2013-11-21T11:27:37+00:00\",\"dateModified\":\"2022-02-01T08:51:06+00:00\",\"author\":{\"@id\":\"https:\/\/emtools.ro\/blog\/#\/schema\/person\/f54fdd06ca546dcf0b14772c20884545\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/emtools.ro\/blog\/despre-lanturile-de-ferastrau-stihl\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/emtools.ro\/blog\/despre-lanturile-de-ferastrau-stihl\/#primaryimage\",\"url\":\"http:\/\/emtools.ro\/blog\/wp-content\/uploads\/2013\/11\/lanturi-stihl.jpg\",\"contentUrl\":\"http:\/\/emtools.ro\/blog\/wp-content\/uploads\/2013\/11\/lanturi-stihl.jpg\",\"width\":440,\"height\":205},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/emtools.ro\/blog\/#website\",\"url\":\"https:\/\/emtools.ro\/blog\/\",\"name\":\"blog emtools.ro\",\"description\":\"Expert Moldova Trading ofera o gama diversa de scule, utilaje si echipamente profesionale moderne, proiectate si fabricate dupa cele mai inalte standarde ale calitatii.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/emtools.ro\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/emtools.ro\/blog\/#\/schema\/person\/f54fdd06ca546dcf0b14772c20884545\",\"name\":\"Mihaela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/emtools.ro\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7f6a28047eea281d2d9e0b1e61819b2277cb223034fd8ad83c552d277bd51374?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7f6a28047eea281d2d9e0b1e61819b2277cb223034fd8ad83c552d277bd51374?s=96&d=mm&r=g\",\"caption\":\"Mihaela\"},\"url\":\"http:\/\/emtools.ro\/blog\/author\/mihaela\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Despre lanturile de ferastrau STIHL - blog emtools.ro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/emtools.ro\/blog\/despre-lanturile-de-ferastrau-stihl\/","og_locale":"en_US","og_type":"article","og_title":"Despre lanturile de ferastrau STIHL - blog emtools.ro","og_description":"Un motoferastrau trebuie sa treaca prin lemn. Pentru aceasta nu are nevoie doar de un motor puternic, ci si de o garnitura de taiere perfect compatibila. Sina de ghidaj, lantul de ferastrau si roata de lant trebuie sa se potriveasca perfect pentru ca puterea motorului sa poata fi transpusa optim in eficienta de taiere autentica. [&hellip;]","og_url":"https:\/\/emtools.ro\/blog\/despre-lanturile-de-ferastrau-stihl\/","og_site_name":"blog emtools.ro","article_publisher":"https:\/\/www.facebook.com\/EMTools","article_published_time":"2013-11-21T11:27:37+00:00","article_modified_time":"2022-02-01T08:51:06+00:00","og_image":[{"width":440,"height":205,"url":"https:\/\/emtools.ro\/blog\/wp-content\/uploads\/2013\/11\/lanturi-stihl.jpg","type":"image\/jpeg"}],"author":"Mihaela","twitter_misc":{"Written by":"Mihaela","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/emtools.ro\/blog\/despre-lanturile-de-ferastrau-stihl\/#article","isPartOf":{"@id":"https:\/\/emtools.ro\/blog\/despre-lanturile-de-ferastrau-stihl\/"},"author":{"name":"Mihaela","@id":"https:\/\/emtools.ro\/blog\/#\/schema\/person\/f54fdd06ca546dcf0b14772c20884545"},"headline":"Despre lanturile de ferastrau STIHL","datePublished":"2013-11-21T11:27:37+00:00","dateModified":"2022-02-01T08:51:06+00:00","mainEntityOfPage":{"@id":"https:\/\/emtools.ro\/blog\/despre-lanturile-de-ferastrau-stihl\/"},"wordCount":810,"commentCount":0,"image":{"@id":"https:\/\/emtools.ro\/blog\/despre-lanturile-de-ferastrau-stihl\/#primaryimage"},"thumbnailUrl":"http:\/\/emtools.ro\/blog\/wp-content\/uploads\/2013\/11\/lanturi-stihl.jpg","keywords":["ferastrau","lanturi de ferastrau","lanturi stihl","stihl"],"articleSection":["Diverse"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/emtools.ro\/blog\/despre-lanturile-de-ferastrau-stihl\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/emtools.ro\/blog\/despre-lanturile-de-ferastrau-stihl\/","url":"https:\/\/emtools.ro\/blog\/despre-lanturile-de-ferastrau-stihl\/","name":"Despre lanturile de ferastrau STIHL - blog emtools.ro","isPartOf":{"@id":"https:\/\/emtools.ro\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/emtools.ro\/blog\/despre-lanturile-de-ferastrau-stihl\/#primaryimage"},"image":{"@id":"https:\/\/emtools.ro\/blog\/despre-lanturile-de-ferastrau-stihl\/#primaryimage"},"thumbnailUrl":"http:\/\/emtools.ro\/blog\/wp-content\/uploads\/2013\/11\/lanturi-stihl.jpg","datePublished":"2013-11-21T11:27:37+00:00","dateModified":"2022-02-01T08:51:06+00:00","author":{"@id":"https:\/\/emtools.ro\/blog\/#\/schema\/person\/f54fdd06ca546dcf0b14772c20884545"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/emtools.ro\/blog\/despre-lanturile-de-ferastrau-stihl\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/emtools.ro\/blog\/despre-lanturile-de-ferastrau-stihl\/#primaryimage","url":"http:\/\/emtools.ro\/blog\/wp-content\/uploads\/2013\/11\/lanturi-stihl.jpg","contentUrl":"http:\/\/emtools.ro\/blog\/wp-content\/uploads\/2013\/11\/lanturi-stihl.jpg","width":440,"height":205},{"@type":"WebSite","@id":"https:\/\/emtools.ro\/blog\/#website","url":"https:\/\/emtools.ro\/blog\/","name":"blog emtools.ro","description":"Expert Moldova Trading ofera o gama diversa de scule, utilaje si echipamente profesionale moderne, proiectate si fabricate dupa cele mai inalte standarde ale calitatii.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/emtools.ro\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/emtools.ro\/blog\/#\/schema\/person\/f54fdd06ca546dcf0b14772c20884545","name":"Mihaela","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/emtools.ro\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7f6a28047eea281d2d9e0b1e61819b2277cb223034fd8ad83c552d277bd51374?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f6a28047eea281d2d9e0b1e61819b2277cb223034fd8ad83c552d277bd51374?s=96&d=mm&r=g","caption":"Mihaela"},"url":"http:\/\/emtools.ro\/blog\/author\/mihaela\/"}]}},"_links":{"self":[{"href":"http:\/\/emtools.ro\/blog\/wp-json\/wp\/v2\/posts\/1076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/emtools.ro\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/emtools.ro\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/emtools.ro\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"http:\/\/emtools.ro\/blog\/wp-json\/wp\/v2\/comments?post=1076"}],"version-history":[{"count":6,"href":"http:\/\/emtools.ro\/blog\/wp-json\/wp\/v2\/posts\/1076\/revisions"}],"predecessor-version":[{"id":2192,"href":"http:\/\/emtools.ro\/blog\/wp-json\/wp\/v2\/posts\/1076\/revisions\/2192"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/emtools.ro\/blog\/wp-json\/wp\/v2\/media\/1080"}],"wp:attachment":[{"href":"http:\/\/emtools.ro\/blog\/wp-json\/wp\/v2\/media?parent=1076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/emtools.ro\/blog\/wp-json\/wp\/v2\/categories?post=1076"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/emtools.ro\/blog\/wp-json\/wp\/v2\/tags?post=1076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}